{"id":397,"date":"2017-02-06T16:57:38","date_gmt":"2017-02-06T14:57:38","guid":{"rendered":"http:\/\/vyzakia.org\/?post_type=portfolio&#038;p=397\/"},"modified":"2017-02-06T16:57:38","modified_gmt":"2017-02-06T14:57:38","slug":"education","status":"publish","type":"portfolio","link":"https:\/\/vyzakia.org\/en\/portfolio-item\/education\/","title":{"rendered":"Education"},"content":{"rendered":"<div  class='togglecontainer av-av_toggle_container-8e0c6e39d39b619a829887bd54fff3ed  avia-builder-el-0  avia-builder-el-no-sibling  toggle_close_all' >\n<section class='av_toggle_section av-av_toggle-b851b7a243b59b0a4152a1a720816c0b'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-1' data-fake-id='#toggle-id-1' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-1' data-slide-speed=\"200\" data-title=\"Elementary School\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Elementary School\" data-aria_expanded=\"Click to collapse: Elementary School\">Elementary School<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-1' aria-labelledby='toggle-toggle-id-1' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><div id=\"6a0409d28a02e\" class=\"gg_gallery_wrap gg_true_gallery gg_standard_gallery gid_353 gg_hidden_ol gg_ol_bottom_mode gg_main_ol_show_on_h \" data-gg_ol=\"default\"  rel=\"353\" data-nores-txt=\"No images found\">              <div class=\"gg_loader\">            <div class=\"ggl_1\"><\/div>            <div class=\"ggl_2\"><\/div>            <div class=\"ggl_3\"><\/div>            <div class=\"ggl_4\"><\/div>        <\/div>  <div class=\"gg_container\"><div class=\"gg_img \" data-gg-url=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_7.jpg\" data-gg-title=\"dimotiko_7\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"0\" rel=\"353\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/vyzakia.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_bf64e79cb448fc001ee83e683df9a18b.jpg\" alt=\"dimotiko_7\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_7.jpg\" alt=\"dimotiko_7\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_6.jpg\" data-gg-title=\"dimotiko_6\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"1\" rel=\"353\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/vyzakia.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_d71c96918e017521d8a5ebe96d4e37ab.jpg\" alt=\"dimotiko_6\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_6.jpg\" alt=\"dimotiko_6\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_5.jpg\" data-gg-title=\"dimotiko_5\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"2\" rel=\"353\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/vyzakia.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_b72afe1c2d720394c69c51061a734e04.jpg\" alt=\"dimotiko_5\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_5.jpg\" alt=\"dimotiko_5\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_4.jpg\" data-gg-title=\"dimotiko_4\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"3\" rel=\"353\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/vyzakia.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_921b4f8dfd94548c8f71adf4314e2ec7.jpg\" alt=\"dimotiko_4\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_4.jpg\" alt=\"dimotiko_4\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_3.jpg\" data-gg-title=\"dimotiko_3\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"4\" rel=\"353\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/vyzakia.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_f9e9f664492f96fcad1c0e8f185fc055.jpg\" alt=\"dimotiko_3\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_3.jpg\" alt=\"dimotiko_3\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_2.jpg\" data-gg-title=\"dimotiko_2\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"5\" rel=\"353\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/vyzakia.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_49987bbe9e3d1bcb092037cd7bc0b42f.jpg\" alt=\"dimotiko_2\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_2.jpg\" alt=\"dimotiko_2\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_1.jpg\" data-gg-title=\"dimotiko_1\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"6\" rel=\"353\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/vyzakia.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_287ecc4838cc73695bc5e39a46d9ef84.jpg\" alt=\"dimotiko_1\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/vyzakia.org\/wp-content\/uploads\/dimotiko_1.jpg\" alt=\"dimotiko_1\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><\/div><div style=\"clear: both;\"><\/div><\/div><script type=\"text\/javascript\">     (function($) {         \"use strict\";              $(document).ready(function($) {             if(typeof(gg_galleries_init) == \"function\") {                gg_galleries_init(\"6a0409d28a02e\");             }        });    })(jQuery);<\/script>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-av_toggle-d3c85e32158bfb807a8f3bac0e6680b1'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-2' data-fake-id='#toggle-id-2' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-2' data-slide-speed=\"200\" data-title=\"Kindergarten\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Kindergarten\" data-aria_expanded=\"Click to collapse: Kindergarten\">Kindergarten<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-2' aria-labelledby='toggle-toggle-id-2' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><div id=\"6a0409d28c596\" class=\"gg_gallery_wrap gg_true_gallery gg_standard_gallery gid_354 gg_hidden_ol gg_ol_bottom_mode gg_main_ol_show_on_h \" data-gg_ol=\"default\"  rel=\"354\" data-nores-txt=\"No images found\">              <div class=\"gg_loader\">            <div class=\"ggl_1\"><\/div>            <div class=\"ggl_2\"><\/div>            <div class=\"ggl_3\"><\/div>            <div class=\"ggl_4\"><\/div>        <\/div>  <div class=\"gg_container\"><div class=\"gg_img \" data-gg-url=\"https:\/\/vyzakia.org\/wp-content\/uploads\/nipiagwgeio_4.jpg\" data-gg-title=\"nipiagwgeio_4\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"0\" rel=\"354\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/vyzakia.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_1701821363d8c2ecdc1bfb0af3288da6.jpg\" alt=\"nipiagwgeio_4\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/vyzakia.org\/wp-content\/uploads\/nipiagwgeio_4.jpg\" alt=\"nipiagwgeio_4\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/vyzakia.org\/wp-content\/uploads\/nipiagwgeio_3.jpg\" data-gg-title=\"nipiagwgeio_3\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"1\" rel=\"354\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/vyzakia.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_c2f7cb2a8e99c7f828aa0ae498ce73e2.jpg\" alt=\"nipiagwgeio_3\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/vyzakia.org\/wp-content\/uploads\/nipiagwgeio_3.jpg\" alt=\"nipiagwgeio_3\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/vyzakia.org\/wp-content\/uploads\/nipiagwgeio_2.jpg\" data-gg-title=\"nipiagwgeio_2\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"2\" rel=\"354\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/vyzakia.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_6d405d63e4be1ddeb1fda09edac8a8b3.jpg\" alt=\"nipiagwgeio_2\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/vyzakia.org\/wp-content\/uploads\/nipiagwgeio_2.jpg\" alt=\"nipiagwgeio_2\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><div class=\"gg_img \" data-gg-url=\"https:\/\/vyzakia.org\/wp-content\/uploads\/nipiagwgeio_1.jpg\" data-gg-title=\"nipiagwgeio_1\" data-gg-author=\"\" data-gg-descr=\"\" data-gg-tags=\"\" data-img-id=\"3\" rel=\"354\">  <div class=\"gg_img_inner\"><div class=\"gg_main_img_wrap\"><img decoding=\"async\" src=\"\" data-gg-lazy-src=\"\/\/vyzakia.org\/wp-content\/uploads\/ewpt_cache\/150x150_100_1_c_FFFFFF_bc5ff8618828152abbbe8e2e94f83c70.jpg\" alt=\"nipiagwgeio_1\" class=\"gg_photo gg_main_thumb\" \/><noscript><img decoding=\"async\" src=\"https:\/\/vyzakia.org\/wp-content\/uploads\/nipiagwgeio_1.jpg\" alt=\"nipiagwgeio_1\" \/><\/noscript><\/div><div class=\"gg_overlays\"><\/div><\/div><\/div><\/div><div style=\"clear: both;\"><\/div><\/div><script type=\"text\/javascript\">     (function($) {         \"use strict\";              $(document).ready(function($) {             if(typeof(gg_galleries_init) == \"function\") {                gg_galleries_init(\"6a0409d28c596\");             }        });    })(jQuery);<\/script>\n<\/div><\/div><\/div><\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":329,"template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[8],"class_list":["post-397","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-what-to-know"],"_links":{"self":[{"href":"https:\/\/vyzakia.org\/en\/wp-json\/wp\/v2\/portfolio\/397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vyzakia.org\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/vyzakia.org\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/vyzakia.org\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/vyzakia.org\/en\/wp-json\/wp\/v2\/portfolio\/397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vyzakia.org\/en\/wp-json\/wp\/v2\/media\/329"}],"wp:attachment":[{"href":"https:\/\/vyzakia.org\/en\/wp-json\/wp\/v2\/media?parent=397"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vyzakia.org\/en\/wp-json\/wp\/v2\/tags?post=397"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/vyzakia.org\/en\/wp-json\/wp\/v2\/portfolio_entries?post=397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}